{"id":2315,"date":"2020-07-22T17:00:25","date_gmt":"2020-07-22T15:00:25","guid":{"rendered":"http:\/\/blnebeit.serveur02.com\/blog\/?p=2315"},"modified":"2020-07-22T17:54:05","modified_gmt":"2020-07-22T15:54:05","slug":"parziale-finale-tipologia-puntata","status":"publish","type":"post","link":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/","title":{"rendered":"Parziale Finale &#8211; Tipologia di Puntata"},"content":{"rendered":"<p>In questo articolo di blog vedremo di spiegare una delle tipologie di <strong><a href=\"https:\/\/scommesse.netbet.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">scommessa<\/a><\/strong> pi\u00f9 utilizzate: Parziale Finale. Questo tipo di giocata consiste nell\u2019effettuare due previsioni in una singola puntata.<\/p>\n<p>La puntata Parziale Finale consiste nell\u2019<strong>indovinare<\/strong> <strong>l\u2019esito della partita sia alla fine del primo tempo che alla fine della gara.<\/strong><\/p>\n<p>Vediamo come funziona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2318 size-full\" src=\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2020\/07\/sd-6.jpg\" alt=\"parziale finale, pallone da calcio\" width=\"1230\" height=\"630\" srcset=\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-6.jpg 1230w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-6-300x154.jpg 300w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-6-1024x524.jpg 1024w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-6-768x393.jpg 768w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-6-990x507.jpg 990w\" sizes=\"auto, (max-width: 1230px) 100vw, 1230px\" \/><\/p>\n<h2>Parziale Finale \u2013 Come Funziona?<\/h2>\n<p>Si chiama Parziale Finale proprio perch\u00e9 in una singola scommessa si dovranno predire entrambi i risultati di fine primo tempo e secondo.<\/p>\n<p>Le quote vengono normalmente visualizzate in questo modo: 1\/1; 1\/X; 1\/2; X\/1; X\/X; X\/2; 2\/1; 2\/X; 2\/2.<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"85\">Puntata<\/td>\n<td width=\"189\">Primo Tempo<\/td>\n<td width=\"170\">Finale<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">1\/1<\/td>\n<td width=\"189\">vantaggio squadra di casa<\/td>\n<td width=\"170\">vince squadra di casa<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">1\/X<\/td>\n<td width=\"189\">vantaggio squadra di casa<\/td>\n<td width=\"170\">pareggio<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">1\/2<\/td>\n<td width=\"189\">vantaggio squadra di casa<\/td>\n<td width=\"170\">vince squadra ospite<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">X\/1<\/td>\n<td width=\"189\">pareggio<\/td>\n<td width=\"170\">vince squadra di casa<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">X\/X<\/td>\n<td width=\"189\">pareggio<\/td>\n<td width=\"170\">pareggio<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">X\/2<\/td>\n<td width=\"189\">pareggio<\/td>\n<td width=\"170\">vince squadra ospite<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">2\/1<\/td>\n<td width=\"189\">vantaggio squadra ospite<\/td>\n<td width=\"170\">vince squadra di casa<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">2\/X<\/td>\n<td width=\"189\">vantaggio squadra ospite<\/td>\n<td width=\"170\">pareggio<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">2\/2<\/td>\n<td width=\"189\">vantaggio squadra ospite<\/td>\n<td width=\"170\">vince squadra ospite<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong><em>Attenzione per\u00f2! <\/em><\/strong><\/p>\n<p>La puntata sar\u00e0 vinta solo nel caso vengano azzeccati <strong>entrambi i pronostici di 1\u00b0T e Finale!<\/strong><\/p>\n<p>Questa tipologia di pronostico, disponibile anche per <strong><a href=\"https:\/\/scommesse.netbet.it\/live-betting\/\" target=\"_blank\" rel=\"noopener noreferrer\">live betting<\/a><\/strong>, \u00e8 rappresentata da quote abbastanza alte soprattutto in caso si punti sulla rimonta. Generalmente, la puntata Parziale Finale 1\/2, che vedrebbe la squadra di casa vincere il primo tempo ma perdere la gara, \u00e8 quotata dalle 4 alle 5 volte in pi\u00f9 rispetto alla puntata diretta sul 2.<\/p>\n<h3><strong>Esempio<\/strong><\/h3>\n<p>Ammettiamo di effettuare tre puntate singole Parziale Finale da 10 euro l\u2019una su 3 match di Serie A.<\/p>\n<ul>\n<li><em>Sassuolo &#8211; Juventus<\/em> : 1\/2 (quota 20.50)<\/li>\n<li><em>Roma &#8211; Verona<\/em> : X\/2 (quota 10.25)<\/li>\n<li><em>Torino &#8211; Genoa<\/em> : 1\/1 (quota 3.35)<\/li>\n<\/ul>\n<p>A fine partita, questi sono i risultati:<\/p>\n<ul>\n<li><em>Sassuolo &#8211; Juventus<\/em> = 1 : 3 (con il risultato sul 1:0 a fine 1\u00b0T)<\/li>\n<li><em>Roma &#8211; Verona<\/em> = 2 : 2 (con il risultato sul 1:0 a fine 1\u00b0T)<\/li>\n<li><em>Torino &#8211; Genoa<\/em> = 4 : 3 (con il risultato sul 2:2 a fine 1\u00b0T)<\/li>\n<\/ul>\n<p>Per la prima puntata, dove abbiamo pronosticato il vantaggio del Sassuolo nel 1\u00b0T con vittoria della Juve, <strong>la puntata \u00e8 VINTA!<\/strong> Stando alle <strong><a href=\"https:\/\/scommesse.netbet.it\/calcio\/\" target=\"_blank\" rel=\"noopener noreferrer\">quote calcio<\/a><\/strong> riportate, la tua vincita sar\u00e0 pari a 205 euro.<\/p>\n<p>Per la seconda puntata, dove abbiamo pronosticato il pareggio nel 1\u00b0T con vittoria del Verona, <strong>la puntata \u00e8 PERSA! <\/strong>Entrambi i risultati non sono stati azzeccati.<\/p>\n<p>Per la terza puntata, dove abbiamo pronosticato il vantaggio nel 1\u00b0T del Torino con vittoria finale dello stesso Torino, <strong>la puntata \u00e8 PERSA!<\/strong> Pur avendo azzeccato il Torino vincente a fine gara, abbiamo sbagliato con il pronostico del fine 1\u00b0T.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2319 size-full\" src=\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2020\/07\/sd-7.jpg\" alt=\"parziale finale, palloni in campo\" width=\"1230\" height=\"630\" srcset=\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-7.jpg 1230w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-7-300x154.jpg 300w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-7-1024x524.jpg 1024w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-7-768x393.jpg 768w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/sd-7-990x507.jpg 990w\" sizes=\"auto, (max-width: 1230px) 100vw, 1230px\" \/><\/p>\n<h2><strong>Su Quali Sport Posso Giocare Parziale Finale?<\/strong><\/h2>\n<p>Questo tipo di giocata \u00e8 <strong>normalmente estesa a tutti gli sport con due tempi<\/strong>. Calcio, basket, rugby, football americano etc.<\/p>\n<p>Tuttavia, possiamo trovare questa tipologia di puntata anche per quegli sport che non hanno due tempi, anche se molto spesso sar\u00e0 chiamata in un altro modo.<\/p>\n<p>Per il <strong>tennis<\/strong> per esempio, molti siti presentano la puntata: 1\u02da Set\/Finale. Questa permette di puntare sulla combinazione esatta tra il vincente del primo set e il vincente dell\u2019incontro.<\/p>\n<p>Un altro esempio di questo \u00e8 l\u2019hockey che, avendo tre tempi a partita, possiede la sua versione di Parziale\/Finale. In questo caso, la puntata potrebbe venir suddivisa in Parziale (primi due tempi) \/ Finale (Finale della partita).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questo articolo di blog vedremo di spiegare una delle tipologie di scommessa pi\u00f9 utilizzate: Parziale Finale. Questo tipo di giocata consiste nell\u2019effettuare due previsioni in una singola puntata. La puntata Parziale Finale consiste nell\u2019indovinare l\u2019esito della partita sia alla fine del primo tempo che alla fine della gara. Vediamo come funziona. Parziale Finale \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2317,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[285,191,286],"class_list":["post-2315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scommesse","tag-parziale-finale","tag-scommesse","tag-tipologia-di-scommessa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parziale Finale. Come Funziona Questa Tipologia di Puntata | NetBet Blog<\/title>\n<meta name=\"description\" content=\"Parziale Finale \u00e8 tra le tipologie di puntata pi\u00f9 conosciute. Andiamo a vedere come funziona nel concreto con qualche esempio e su quali sport si applica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parziale Finale. Come Funziona Questa Tipologia di Puntata | NetBet Blog\" \/>\n<meta property=\"og:description\" content=\"Parziale Finale \u00e8 tra le tipologie di puntata pi\u00f9 conosciute. Andiamo a vedere come funziona nel concreto con qualche esempio e su quali sport si applica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-22T15:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-22T15:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1230\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\"},\"headline\":\"Parziale Finale &#8211; Tipologia di Puntata\",\"datePublished\":\"2020-07-22T15:00:25+00:00\",\"dateModified\":\"2020-07-22T15:54:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\"},\"wordCount\":511,\"image\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg\",\"keywords\":[\"parziale finale\",\"scommesse\",\"tipologia di scommessa\"],\"articleSection\":[\"Scommesse\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\",\"url\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\",\"name\":\"Parziale Finale. Come Funziona Questa Tipologia di Puntata | NetBet Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg\",\"datePublished\":\"2020-07-22T15:00:25+00:00\",\"dateModified\":\"2020-07-22T15:54:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\"},\"description\":\"Parziale Finale \u00e8 tra le tipologie di puntata pi\u00f9 conosciute. Andiamo a vedere come funziona nel concreto con qualche esempio e su quali sport si applica.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage\",\"url\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg\",\"contentUrl\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg\",\"width\":1230,\"height\":630,\"caption\":\"parziale finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.netbet.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parziale Finale &#8211; Tipologia di Puntata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#website\",\"url\":\"https:\/\/www.netbet.it\/blog\/\",\"name\":\"NetBet Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netbet.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.netbet.it\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parziale Finale. Come Funziona Questa Tipologia di Puntata | NetBet Blog","description":"Parziale Finale \u00e8 tra le tipologie di puntata pi\u00f9 conosciute. Andiamo a vedere come funziona nel concreto con qualche esempio e su quali sport si applica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/","og_locale":"it_IT","og_type":"article","og_title":"Parziale Finale. Come Funziona Questa Tipologia di Puntata | NetBet Blog","og_description":"Parziale Finale \u00e8 tra le tipologie di puntata pi\u00f9 conosciute. Andiamo a vedere come funziona nel concreto con qualche esempio e su quali sport si applica.","og_url":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/","og_site_name":"NetBet Blog","article_published_time":"2020-07-22T15:00:25+00:00","article_modified_time":"2020-07-22T15:54:05+00:00","og_image":[{"width":1230,"height":630,"url":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#article","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/"},"author":{"name":"admin","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"headline":"Parziale Finale &#8211; Tipologia di Puntata","datePublished":"2020-07-22T15:00:25+00:00","dateModified":"2020-07-22T15:54:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/"},"wordCount":511,"image":{"@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg","keywords":["parziale finale","scommesse","tipologia di scommessa"],"articleSection":["Scommesse"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/","url":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/","name":"Parziale Finale. Come Funziona Questa Tipologia di Puntata | NetBet Blog","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage"},"image":{"@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg","datePublished":"2020-07-22T15:00:25+00:00","dateModified":"2020-07-22T15:54:05+00:00","author":{"@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"description":"Parziale Finale \u00e8 tra le tipologie di puntata pi\u00f9 conosciute. Andiamo a vedere come funziona nel concreto con qualche esempio e su quali sport si applica.","breadcrumb":{"@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#primaryimage","url":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg","contentUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2020\/07\/1-7.jpg","width":1230,"height":630,"caption":"parziale finale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.netbet.it\/blog\/parziale-finale-tipologia-puntata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netbet.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Parziale Finale &#8211; Tipologia di Puntata"}]},{"@type":"WebSite","@id":"https:\/\/www.netbet.it\/blog\/#website","url":"https:\/\/www.netbet.it\/blog\/","name":"NetBet Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netbet.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.netbet.it\/blog\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/2315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/comments?post=2315"}],"version-history":[{"count":2,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/2315\/revisions"}],"predecessor-version":[{"id":2321,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/2315\/revisions\/2321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media\/2317"}],"wp:attachment":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media?parent=2315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/categories?post=2315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/tags?post=2315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}