{"id":3965,"date":"2021-06-16T17:06:13","date_gmt":"2021-06-16T15:06:13","guid":{"rendered":"http:\/\/blnebeit.serveur02.com\/blog\/?p=3965"},"modified":"2021-06-14T12:13:57","modified_gmt":"2021-06-14T10:13:57","slug":"sport-che-bruciano-calorie","status":"publish","type":"post","link":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/","title":{"rendered":"Gli Sport che Bruciano pi\u00f9 Calorie"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Se siete alla ricerca di sport che bruciano pi\u00f9 calorie allora questo \u00e8 il posto giusto per voi. Nel corso dei prossimi paragrafi, infatti, vedremo quali sono i principali sport grazie ai quali potrete bruciare calorie nella maniera pi\u00f9 veloce, e quindi perdere peso.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo, infatti, \u00e8 un problema molto comune soprattutto ai giorni nostri. Visto che siamo presi dal lavoro e da mille impegni, c\u2019\u00e8 davvero poco tempo per dedicarsi ad un po\u2019 di rilassante sport che aiuti anche a perdere peso. Ed \u00e8 per questo che tutti, o quasi, soprattutto quando si avvicina o l\u2019estate o dopo periodi in cui ci si lascia un po\u2019 andare dal punto di vista culinario (vedi Natale e Pasqua) vanno alla ricerca degli sport che bruciano calorie in maniera pi\u00f9 veloce.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prima, per\u00f2, sottolineiamo un aspetto. Nel corso di questo articolo vi parleremo di questi sport e di quante calorie si bruciano in linea generale. Ma dovete sapere che il dispendio energetico cambia da persona a persona in base al peso, ai muscoli, se \u00e8 gi\u00e0 allenato oppure no. Insomma, ci sono davvero tante variabili di cui bisogna tenere conto.\u00a0<\/span><\/p>\n<h2><strong>Sport che Bruciano Calorie<\/strong><\/h2>\n<h3><strong>Trekking<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">\u00c8 uno degli sport pi\u00f9 affascinanti soprattutto per gli amanti della natura. Ovviamente, si tratta di percorrere dei sentieri immersi nel verde, spesso su colline e montagne per arrivare sino in cima. I panorami sono mozzafiato ed \u00e8 anche un toccasana per la mente. Si smette, infatti, di pensare ai problemi e al lavoro e ci si dedica totalmente a godersi il momento.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E se ci aggiungiamo che spesso i telefoni non prendono la linea, tutto diventa perfetto perch\u00e9 nessuno potr\u00e0 disturbarvi. Con questa disciplina si consumano circa 400 calorie all\u2019ora e se considerate che un percorso dura molto pi\u00f9 di un\u2019ora, il consumo diventa interessante.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3526 size-full\" src=\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg\" alt=\"\" width=\"1230\" height=\"630\" \/><\/p>\n<h3><strong>Basket<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Uno degli sport pi\u00f9 famosi al mondo, anche dal punto di vista del <\/span><strong><a href=\"https:\/\/scommesse.netbet.it\/live-betting\/\" target=\"_blank\" rel=\"noopener\">live betting<\/a><\/strong><span style=\"font-weight: 400;\">, ovvero il basket \u00e8 una delle discipline in cui si comunano pi\u00f9 calorie. Ed in effetti, non era difficile prevederlo, visto che parliamo comunque di una disciplina molto veloce e con repentini cambi di campo, salti e scontri fisici. Inoltre, c\u2019\u00e8 anche un discreto consumo energetico. Si parla, infatti, di circa 500 calorie all\u2019ora e non \u00e8 per niente male.\u00a0<\/span><\/p>\n<h3><strong>Ciclismo\u00a0<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Questo \u00e8 sicuramente tra gli sport che bruciano pi\u00f9 calorie, ma c\u2019\u00e8 da considerare un aspetto. Il ciclismo, infatti, pu\u00f2 essere fatto in diversi modo. \u00c8 possibile fare una semplice passeggiata su un percorso di pianura e per un breve tratto, oppure spingersi in scalate di montagna. Da questo, ovviamente, dipende il consumo di energia e quindi di calorie. In generale, comunque, si possono consumare dalle 500 alle 880 calorie in una sola ora.<\/span><\/p>\n<h3><strong>Il Tennis tra gli Sport che Bruciano Calorie<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Altro sport estremamente famoso anche tra le <\/span><strong><a href=\"https:\/\/scommesse.netbet.it\/\" target=\"_blank\" rel=\"noopener\">scommesse sportive<\/a><\/strong><span style=\"font-weight: 400;\">. Il Tennis rientra facilmente in questa categoria visto che in ogni partita si effettuano centinaia di scatti sia da una parte all\u2019altra del campo sia in avanti. \u00c8 necessaria, quindi, una certa forza nelle gambe ma non solo. Anche le braccia devono essere ben allenate e nel corso della gara fanno uno sforzo importante. Ecco perch\u00e9 una partita di tennis porta a consumare pota a consumare quasi 600 calorie.\u00a0<\/span><\/p>\n<h3><strong>Nuoto\u00a0<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">In questo sport vengono messi moto tutti i muscoli del corpo nello stesso momento, ma c\u2019\u00e8 un altro aspetto a cui bisogna prestare attenzione. In pratica, quando si nuota c\u2019\u00e8 bisogno di una certa concentrazione a livello mentale perch\u00e9 bisogna coordinare tutti i movimenti. Questo significa che il consumo diventa ancora pi\u00f9 intenso, ed \u00e8 per questo che si arriva ad oltre 600 calorie in soli 60 minuti di attivit\u00e0.\u00a0<\/span><\/p>\n<h3><strong>Salto della Corda<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">\u00c8 uno degli sport che brucia pi\u00f9 calorie che costa meno. Basta solo una corda ed il gioco \u00e8 fatto. Questa attivit\u00e0 che pu\u00f2 sembrare estremamente semplice, infatti, \u00e8 capace di metter in modo tutti i muscoli del corpo e, come per il nuoto, \u00e8 necessaria una particolare coordinazione. In caso contrario, infatti, si rischia di finire a terra e anche di farsi male. Ecco perch\u00e9 si consumano oltre 77 calorie saltando la corda per un\u2019ora.\u00a0<\/span><\/p>\n<h3><strong>Corsa veloce<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Eravate sopresi che ancora non avevamo parlato della corsa veloce? Il motivo \u00e8 che si tratta di uno dei quegli sport in cui si bruciano pi\u00f9 calorie e quindi arriva quasi alla fine. Ovviamente, abbiamo specificato corsa veloce perch\u00e9 si tratta di un\u2019attivit\u00e0 totalmente diversa dal camminare o dal jogging. In questo caso, infatti, c\u2019\u00e8 bisogno di spingere sull\u2019acceleratore e portare lo sforzo fisico ai massimi livelli, senza considerare che i battiti cardiaci aumentano e quindi il consumo si incrementa considerevolmente. Infatti, parliamo di circa 800 calorie in una sola ora di attivit\u00e0.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3206 size-full\" src=\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/01\/no-logo-2-1.jpg\" alt=\"muhammad ali sul ring\" width=\"1230\" height=\"630\" srcset=\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2021\/01\/no-logo-2-1.jpg 1230w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2021\/01\/no-logo-2-1-300x154.jpg 300w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2021\/01\/no-logo-2-1-1024x524.jpg 1024w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2021\/01\/no-logo-2-1-768x393.jpg 768w, https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2021\/01\/no-logo-2-1-990x507.jpg 990w\" sizes=\"auto, (max-width: 1230px) 100vw, 1230px\" \/><\/p>\n<h3><strong>Boxe\u00a0\u00a0<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">La boxe \u00e8 il primo tra gli sport che brucia pi\u00f9 calorie. Se non siete appassionati di questa disciplina, probabilmente la considerate solo uno sporto in cui ci si prende a pugni. La verit\u00e0, invece, \u00e8 che i boxeur non stanno mai fermi sul ring, fanno continui scatti e, soprattutto, si picchiano abbastanza forte. Questo li porta ad avere anche la massima concentrazione per evitare i colpi dell\u2019avversario oltre ad avere il pregio di scaricare lo stress e liberare la mente. Un\u2019ora di boxe vi porter\u00e0 a consumare ben 900 calorie.\u00a0<\/span><\/p>\n<h3><strong>Calcio<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Forse non tutti credevano che questo sport potesse addirittura essere il secondo tra gli sport che bruciano calorie. Ma se ci pensate, il motivo \u00e8 abbastanza semplice. In ogni partita, infatti, pur senza rendersene conto, si percorrono correndo diversi chilometri. Inoltre, ci sono scontri fisici ed \u00e8 sempre necessario mantenere la concentrazione al massimo per evitare ogni sorta di errori. Il consumo totale, quindi, \u00e8 di circa 850 calorie. Piccola parentesi: il ruolo del portiere non consuma quanto gli altri giocatori perch\u00e9 il suo sforzo in campo, almeno dal punto di vista fisico non \u00e8 continuo.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se siete alla ricerca di sport che bruciano pi\u00f9 calorie allora questo \u00e8 il posto giusto per voi. Nel corso dei prossimi paragrafi, infatti, vedremo quali sono i principali sport grazie ai quali potrete bruciare calorie nella maniera pi\u00f9 veloce, e quindi perdere peso.\u00a0 Questo, infatti, \u00e8 un problema molto comune soprattutto ai giorni nostri. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3965","post","type-post","status-publish","format-standard","hentry","category-scommesse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecco Svelati gli Sport che Bruciano Calorie pi\u00f9 di Tutti | NetBet Blog<\/title>\n<meta name=\"description\" content=\"In questo articolo vedremo insieme quasi sono gli sport che bruciano pi\u00f9 calorie in generale, e a quanto equivale il consumo in un\u2019ora di attivit\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecco Svelati gli Sport che Bruciano Calorie pi\u00f9 di Tutti | NetBet Blog\" \/>\n<meta property=\"og:description\" content=\"In questo articolo vedremo insieme quasi sono gli sport che bruciano pi\u00f9 calorie in generale, e a quanto equivale il consumo in un\u2019ora di attivit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-16T15:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\"},\"headline\":\"Gli Sport che Bruciano pi\u00f9 Calorie\",\"datePublished\":\"2021-06-16T15:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\"},\"wordCount\":953,\"image\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg\",\"articleSection\":[\"Scommesse\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\",\"url\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\",\"name\":\"Ecco Svelati gli Sport che Bruciano Calorie pi\u00f9 di Tutti | NetBet Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg\",\"datePublished\":\"2021-06-16T15:06:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\"},\"description\":\"In questo articolo vedremo insieme quasi sono gli sport che bruciano pi\u00f9 calorie in generale, e a quanto equivale il consumo in un\u2019ora di attivit\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage\",\"url\":\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg\",\"contentUrl\":\"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.netbet.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli Sport che Bruciano pi\u00f9 Calorie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#website\",\"url\":\"https:\/\/www.netbet.it\/blog\/\",\"name\":\"NetBet Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netbet.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.netbet.it\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecco Svelati gli Sport che Bruciano Calorie pi\u00f9 di Tutti | NetBet Blog","description":"In questo articolo vedremo insieme quasi sono gli sport che bruciano pi\u00f9 calorie in generale, e a quanto equivale il consumo in un\u2019ora di attivit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/","og_locale":"it_IT","og_type":"article","og_title":"Ecco Svelati gli Sport che Bruciano Calorie pi\u00f9 di Tutti | NetBet Blog","og_description":"In questo articolo vedremo insieme quasi sono gli sport che bruciano pi\u00f9 calorie in generale, e a quanto equivale il consumo in un\u2019ora di attivit\u00e0.","og_url":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/","og_site_name":"NetBet Blog","article_published_time":"2021-06-16T15:06:13+00:00","og_image":[{"url":"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#article","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/"},"author":{"name":"admin","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"headline":"Gli Sport che Bruciano pi\u00f9 Calorie","datePublished":"2021-06-16T15:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/"},"wordCount":953,"image":{"@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage"},"thumbnailUrl":"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg","articleSection":["Scommesse"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/","url":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/","name":"Ecco Svelati gli Sport che Bruciano Calorie pi\u00f9 di Tutti | NetBet Blog","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage"},"image":{"@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage"},"thumbnailUrl":"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg","datePublished":"2021-06-16T15:06:13+00:00","author":{"@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"description":"In questo articolo vedremo insieme quasi sono gli sport che bruciano pi\u00f9 calorie in generale, e a quanto equivale il consumo in un\u2019ora di attivit\u00e0.","breadcrumb":{"@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#primaryimage","url":"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg","contentUrl":"http:\/\/blnebeit.serveur02.com\/blog\/wp-content\/uploads\/2021\/03\/no-logo-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.netbet.it\/blog\/sport-che-bruciano-calorie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netbet.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Gli Sport che Bruciano pi\u00f9 Calorie"}]},{"@type":"WebSite","@id":"https:\/\/www.netbet.it\/blog\/#website","url":"https:\/\/www.netbet.it\/blog\/","name":"NetBet Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netbet.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.netbet.it\/blog\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/3965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/comments?post=3965"}],"version-history":[{"count":1,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/3965\/revisions"}],"predecessor-version":[{"id":3968,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/3965\/revisions\/3968"}],"wp:attachment":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media?parent=3965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/categories?post=3965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/tags?post=3965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}