{"id":5500,"date":"2023-04-17T17:16:16","date_gmt":"2023-04-17T15:16:16","guid":{"rendered":"https:\/\/blog.netbet.it\/blog\/?p=5500"},"modified":"2023-04-26T20:17:21","modified_gmt":"2023-04-26T18:17:21","slug":"casino-lisbona","status":"publish","type":"post","link":"https:\/\/www.netbet.it\/blog\/casino-lisbona\/","title":{"rendered":"5 Luoghi da Non Perdere a Lisbona"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Lisbona \u00e8 una delle citt\u00e0 pi\u00f9 intriganti ed interessanti in tutta Europa e nel Mondo e ogni anno milioni la visitano milioni di persone. In questo articolo vogliamo scoprire le cinque migliori attrazioni da visitare assolutamente. Inoltre, ne aggiungeremo un\u2019altra che gli appassionati di<\/span><strong><a href=\"https:\/\/casino.netbet.it\/slots\" target=\"_blank\" rel=\"noopener\"> slot machine<\/a><\/strong><span style=\"font-weight: 400;\"> online non potranno perdersi e cio\u00e8 il Casino Lisbona (o Lisboa).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ma procediamo con ordine e scopriamo tutto nel dettaglio. In questo modo, quindi, qualora aveste in mente un viaggio in Portogallo, non rischierete di perdervi nulla.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prima di passare al fulcro del nostro discorso, poi, vogliamo raccontarvi una piccola curiosit\u00e0 che forse non tutti conoscono. Lisbona, infatti, \u00e8 anche definita la citt\u00e0 dei sette colli, proprio come Roma.<\/span><\/p>\n<h2><strong>Cinque Cose da Vedere a Lisbona<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Di seguito, ci soffermeremo sulle cinque principali attrazioni che non dovete assolutamente perdervi a Lisbona. Attenzione, per\u00f2, perch\u00e9 ce ne sono tantissime altre che meritano sicuramente una visita. Lisbona, infatti, \u00e8 una citt\u00e0 stupenda sotto tantissimi punti di vista e ognuno pu\u00f2 trovare i propri monumenti preferiti e le esperienze indimenticabili.<\/span><\/p>\n<h3><strong>Torre di Bel\u00e9m<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">La Torre di Bel\u00e9m \u00e8 praticamente uno dei monumenti pi\u00f9 famosi e possiamo dire emblematici di Lisbona. Proprio per questo motivo \u00e8 uno di quei luoghi che nessun turista vorr\u00e0 perdere.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 stata costruita nel 1515 ed \u00e8 situata lungo la riva del fiume Tago. Il suo scopo era quello di proteggere la citt\u00e0 dalle invasioni via mare visto che dall\u2019alto erano subito visibili le imbarcazioni nemiche. Attualmente \u00e8 un museo e Patrimonio culturale dell&#8217;Umanit\u00e0 secondo l&#8217;Unesco. Il suo essere un punto riferimento per gli esploratori e i viaggiatori, infatti, \u00e8 stato ritenuto fondamentale nella storia.<\/span><\/p>\n<h3><strong>Castello di San Giorgio<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Se avete gi\u00e0 visto qualche foto in giro, capirete da soli il motivo per cui il Castello di San Giorgio \u00e8 un&#8217;altra attrazione iconica di Lisbona. \u00c8 situato sulla cima di una delle sette colline delle citt\u00e0 e offre una splendida vista dall\u2019alto sia della citt\u00e0 che del fiume Tago.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il Castello \u00e8 stato costruito migliaia di anni fa e nel corso del tempo ha subito molte trasformazioni.<\/span><\/p>\n<h3><strong>Tram 28<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Questa \u00e8 un&#8217;attrazione itinerante, oltre ad essere uno dei migliori modi per osservare la citt\u00e0 in tutte le sue particolarit\u00e0 e bellezze. Il Tram 28, infatti, \u00e8 davvero unico sia perch\u00e9 percorre gran parte della citt\u00e0 sia perch\u00e9 passa attraverso delle viuzze strettissime e lungo i principali luoghi di interesse della capitale portoghese.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Attenzione, per\u00f2, a scegliere l&#8217;orario giusto visto che il tram \u00e8, ovviamente, molto ricercato. Questo significa, quindi, che potrebbero esserci lunghe code per salirci.<\/span><\/p>\n<h3><strong>Monastero di San Girolamo<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Il Monasteros dos Jeronimos \u00e8 situato nel quartiere Bel\u00e9m di Lisbona ed \u00e8 un altro importante luogo da non perdere. Fu costruito per volere del Re Manuele I che intendeva festeggiare il ritorno del navigatore Vasco da Gama nel 1502. Nel 1983 l\u2019Unesco lo ha inserito tra i beni Patrimonio dell&#8217;Umanit\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Inoltre, \u00e8 famoso anche per un fatto storico. Nel 2007, infatti, \u00e8 stato il luogo scelto per la firma del Trattato di Lisbona, ovvero la serie di atti su cui si fonda tutta l\u2019Unione Europea.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Chiado<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Naturalmente, oltre a monasteri e castelli, non poteva mancare un quartiere alla moda e in cui semplicemente passeggiare o godersi un caff\u00e8. E la scelta migliore in questo caso \u00e8 il Chiado, uno dei quartieri pi\u00f9 famosi di Lisbona.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vi troverete caf\u00e8, ristoranti di altissimo livello, boutique e tante librerie. Inoltre, \u00e8 davvero pittoresco e merita sicuramente una visita.<\/span><\/p>\n<h2><strong>Il Casino Lisbona<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Come gi\u00e0 preannunciato all&#8217;inizio di questo articolo, oltre alle cinque migliori attrazioni da non perdere, la citt\u00e0 offre qualcosa anche per gli appassionati di giochi: il<\/span><strong><a href=\"https:\/\/www.netbet.it\/blog\/casino-lisboa\/\" target=\"_blank\" rel=\"noopener\"> Casin\u00f2 di Lisbona<\/a><\/strong><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 la struttura terrestre pi\u00f9 grande del Portogallo e anche tra le pi\u00f9 grandi in tutta Europa. Si trova nei pressi del Parque das Na\u00e7\u00f5es, vicino alle Ocean\u00e1rio. All&#8217;interno, ovviamente, \u00e8 possibile trovare una vastissima gamma di giochi, ma anche spettacoli, bar e ristoranti.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Come Accedere al Casin\u00f2 di Lisbona<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">L\u2019accesso alle sale dedicate al gioco \u00e8 riservato esclusivamente alle persone che hanno compiuto almeno 18 anni. Per questo motivo, quindi, \u00e8 richiesta la verifica della propria et\u00e0 all\u2019ingresso. Di conseguenza, non dimenticate di portare con voi sempre un documento d&#8217;identit\u00e0 valido con foto. In caso contrario, infatti, rischierete di restare fuori.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Inoltre, all\u2019ingresso pu\u00f2 essere fatta una selezione anche in base al vostro abbigliamento. Evitate, quindi, di indossare un abbigliamento poco consono, come ciabatte, smanicati e pantaloncini corti, oltre a cappelli. Anche in questo caso, infatti, la direzione si riserva sempre il diritto di non consentire l\u2019accesso alla sala da gioco.<\/span><\/p>\n<h3><strong>I Giochi del Casino Lisboa\u00a0<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">La lista di tavoli da gioco disponibili nel casin\u00f2 Lisbona \u00e8 davvero lunga. Potrete puntare, ad esempio, su diversi tipi di blackjack, roulette, il Macau baccarat, oltre al Poker caraibico. Inoltre, troverete anche il French Bank, un gioco da tavolo nato in Portogallo e per questo molto famoso anche nel Casino Lisbona. Si tratta di un gioco con i dadi in cui, per\u00f2, non sono i giocatori a tirarli, ma bens\u00ec il croupier. Nel corso del tempo, poi, \u00e8 divenuto famoso anche in Spagna con il nome &#8220;Dados Portugueses&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Naturalmente, poi, non mancano le sale riservate alle slot machine. Tra queste, ad esempio, potreste trovare giochi molto famosi anche nei casin\u00f2 online come la slot<\/span><strong><a href=\"https:\/\/casino.netbet.it\/gioco\/fruit-shop\" target=\"_blank\" rel=\"noopener\"> Fruit Shop<\/a><\/strong><span style=\"font-weight: 400;\">, oppure diversi giochi Megaways.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Infine, ricordate sempre di puntare con la massima responsabilit\u00e0 e di giocare per divertirvi.<\/span><\/p>\n<h2><strong>Conclusione<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Eccoci giunti alla fine del nostro articolo sulle cinque principali attrazioni da visitare nella capitale portoghese, oltre al Casino Lisbona.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per restare aggiornati, i nostri esperti del<\/span><a href=\"https:\/\/casino.netbet.it\/\"><span style=\"font-weight: 400;\"> NetBet casino online<\/span><\/a><span style=\"font-weight: 400;\"> hanno realizzato diverse guide sulle principali strutture da gioco nel mondo, oltre a news e curiosit\u00e0 sui giochi e strategie varie.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lisbona \u00e8 una delle citt\u00e0 pi\u00f9 intriganti ed interessanti in tutta Europa e nel Mondo e ogni anno milioni la visitano milioni di persone. In questo articolo vogliamo scoprire le cinque migliori attrazioni da visitare assolutamente. Inoltre, ne aggiungeremo un\u2019altra che gli appassionati di slot machine online non potranno perdersi e cio\u00e8 il Casino Lisbona [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4795,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oltre al Casino Lisbona, 5 Luoghi da Non Perdere | NetBet Blog<\/title>\n<meta name=\"description\" content=\"Oltre al Casino Lisbona, scopriamo quali sono i 5 luoghi che non bisogna assolutamente perdere in una visita nella capitale portoghese.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oltre al Casino Lisbona, 5 Luoghi da Non Perdere | NetBet Blog\" \/>\n<meta property=\"og:description\" content=\"Oltre al Casino Lisbona, scopriamo quali sono i 5 luoghi che non bisogna assolutamente perdere in una visita nella capitale portoghese.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T15:16:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T18:17:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1230\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/#\\\/schema\\\/person\\\/46b4b3318d54ed292a985534108c6b57\"},\"headline\":\"5 Luoghi da Non Perdere a Lisbona\",\"datePublished\":\"2023-04-17T15:16:16+00:00\",\"dateModified\":\"2023-04-26T18:17:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/\"},\"wordCount\":943,\"image\":{\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1-3.jpg\",\"articleSection\":[\"Casin\u00f3\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/\",\"url\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/\",\"name\":\"Oltre al Casino Lisbona, 5 Luoghi da Non Perdere | NetBet Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1-3.jpg\",\"datePublished\":\"2023-04-17T15:16:16+00:00\",\"dateModified\":\"2023-04-26T18:17:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/#\\\/schema\\\/person\\\/46b4b3318d54ed292a985534108c6b57\"},\"description\":\"Oltre al Casino Lisbona, scopriamo quali sono i 5 luoghi che non bisogna assolutamente perdere in una visita nella capitale portoghese.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1-3.jpg\",\"width\":1230,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.netbet.it\\\/blog\\\/casino-lisbona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Luoghi da Non Perdere a Lisbona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/\",\"name\":\"NetBet Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/#\\\/schema\\\/person\\\/46b4b3318d54ed292a985534108c6b57\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.netbet.it\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oltre al Casino Lisbona, 5 Luoghi da Non Perdere | NetBet Blog","description":"Oltre al Casino Lisbona, scopriamo quali sono i 5 luoghi che non bisogna assolutamente perdere in una visita nella capitale portoghese.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/","og_locale":"it_IT","og_type":"article","og_title":"Oltre al Casino Lisbona, 5 Luoghi da Non Perdere | NetBet Blog","og_description":"Oltre al Casino Lisbona, scopriamo quali sono i 5 luoghi che non bisogna assolutamente perdere in una visita nella capitale portoghese.","og_url":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/","og_site_name":"NetBet Blog","article_published_time":"2023-04-17T15:16:16+00:00","article_modified_time":"2023-04-26T18:17:21+00:00","og_image":[{"width":1230,"height":630,"url":"https:\/\/blog.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/1-3.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#article","isPartOf":{"@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/"},"author":{"name":"admin","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"headline":"5 Luoghi da Non Perdere a Lisbona","datePublished":"2023-04-17T15:16:16+00:00","dateModified":"2023-04-26T18:17:21+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/"},"wordCount":943,"image":{"@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/1-3.jpg","articleSection":["Casin\u00f3"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/","url":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/","name":"Oltre al Casino Lisbona, 5 Luoghi da Non Perdere | NetBet Blog","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#primaryimage"},"image":{"@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/1-3.jpg","datePublished":"2023-04-17T15:16:16+00:00","dateModified":"2023-04-26T18:17:21+00:00","author":{"@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"description":"Oltre al Casino Lisbona, scopriamo quali sono i 5 luoghi che non bisogna assolutamente perdere in una visita nella capitale portoghese.","breadcrumb":{"@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.netbet.it\/blog\/casino-lisbona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#primaryimage","url":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/1-3.jpg","contentUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/1-3.jpg","width":1230,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/blog.netbet.it\/blog\/casino-lisbona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netbet.it\/blog\/"},{"@type":"ListItem","position":2,"name":"5 Luoghi da Non Perdere a Lisbona"}]},{"@type":"WebSite","@id":"https:\/\/www.netbet.it\/blog\/#website","url":"https:\/\/www.netbet.it\/blog\/","name":"NetBet Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netbet.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.netbet.it\/blog\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/5500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/comments?post=5500"}],"version-history":[{"count":1,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/5500\/revisions"}],"predecessor-version":[{"id":5502,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/5500\/revisions\/5502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media\/4795"}],"wp:attachment":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media?parent=5500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/categories?post=5500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/tags?post=5500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}