{"id":5503,"date":"2023-04-21T17:17:35","date_gmt":"2023-04-21T15:17:35","guid":{"rendered":"https:\/\/blog.netbet.it\/blog\/?p=5503"},"modified":"2023-04-26T20:18:16","modified_gmt":"2023-04-26T18:18:16","slug":"ciclismo-in-francia","status":"publish","type":"post","link":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/","title":{"rendered":"Ciclismo In Francia: Parigi-Roubaix"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Se siete degli appassionati di ciclismo, saprete subito di cosa stiamo parlando se vi nominiamo la \u201cRegina delle Classiche\u201d. Qualora, invece, il nome non vi dicesse nulla, allora questo \u00e8 il posto giusto per voi. Nel corso di questo articolo, infatti, vedremo in maniera dettagliata tutte le caratteristiche pi\u00f9 importanti e le principali informazioni su una delle gare di ciclismo pi\u00f9 note al mondo: la Parigi-Roubaix.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questa gara, che per il ciclismo in Francia, insieme al Tour de France, rappresenta i cardini del movimento, nasce tantissimi anni fa. E la sua storia \u00e8 costellata di episodi cursori, record e particolarit\u00e0. Nei prossimi paragrafi vedremo nel dettaglio tutti gli aspetti pi\u00f9 importanti che ogni appassionato di<\/span><strong><a href=\"https:\/\/scommesse.netbet.it\/ciclismo\/\" target=\"_blank\" rel=\"noopener\"> scommesse ciclismo<\/a><\/strong><span style=\"font-weight: 400;\"> dovrebbe sicuramente conoscere.<\/span><\/p>\n<h2><strong>Cos\u2019\u00e8 la Parigi-Roubaix?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Questa gara da molti \u00e8 definita anche come &#8220;l&#8217;Inferno del Nord&#8221; (l&#8217;Enfer du Nord in francese). Ci\u00f2, quindi, ci consente di capire subito che non si tratta di qualcosa di semplice. Al contrario, infatti, \u00e8 una delle gare pi\u00f9 affascinanti dell&#8217;intero circuito, ma anche una delle pi\u00f9 pesanti. Si svolge in un\u2019unica giornata, solitamente a Pasqua o comunque ad aprile, e il percorso \u00e8 spesso superiore ai 250 chilometri. C\u2019\u00e8 da dire, comunque, che la misura tende a cambiare di anno in anno in base alla partenza o all&#8217;arrivo prestabilito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La durezza della gara, poi, oltre alla lunghezza, \u00e8 dovuta a due fattori particolari, e cio\u00e8 le condizioni atmosferiche che nel nord della Francia sono spesso proibitive, quindi con vento e pioggia, e al pav\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tra le gare di ciclismo in Francia, cos\u00ec come nel resto dell\u2019Europa e nel Mondo, la Parigi-Roubaix \u00e8 una delle pochissime che prevede lunghi tratti sul pav\u00e9. Bisogna sapere, infatti, che il pav\u00e9 \u00e8 un tipo di selciato composto da cubi di porfido o di pietra o ciottoli. Di conseguenza, i ciclisti e le loro bici sono sottoposti a tantissime vibrazioni, pi\u00f9 o meno forti. Tali vibrazioni, oltre a rendere decisamente scomoda l\u2019andatura, provocano spesso tantissimi problemi, ed in particolari cadute e forature.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Infine, bisogna considerare che le gare durano oltre 5 ore. Quindi, tenendo conto di tutti gli elementi analizzati fino a questo momento, si intuiscono facilmente i motivi per cui questa gara\u00a0\u00e8 ritenuta una delle pi\u00f9 dure in assoluto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Anche per questo, perci\u00f2, nonostante la lunghissima storia della Parigi-Roubaix, non si \u00e8 mai pensato di creare una versione femminile, almeno fino al 2020. A partire da quest\u2019anno, infatti, anche le cicliste hanno l&#8217;allora Parigi-Roubaix. La lunghezza del percorso \u00e8 inferiore rispetto alla versione maschile, ma la durezza della gara resta comunque elevata.<\/span><\/p>\n<h2><strong>Ciclismo in Francia &#8211; Storia della Parigi Roubaix<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Iniziamo col dirvi che parlare nel dettaglio della storia del ciclismo in Francia o della Parigi-Roubaix nel dettaglio sarebbe impossibile.\u00a0Si tratta, infatti, di un periodo di oltre 120 anni e raccontare tutto in poche righe \u00e8 davvero difficile. Ci limiteremo, quindi, ad alcuni momenti importanti che hanno contraddistinto questo evento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La prima gara fu organizzata nel 1896 e l\u2019idea venne a Theodore Vienne e Maurice Perez, due filatori di Roubaix. Questi, infatti, avevano costruito un velodromo in citt\u00e0. Per dargli risalto, quindi, cercarono di dar vita ad una gara ciclistica che iniziasse da Parigi e terminasse nel nuovo impianto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;organizzazione fu affidata a due giornalisti del \u201cLe Velo\u201d e cio\u00e8 Victor Breyer e Paolo Meyan. Quest&#8217;ultimo si rec\u00f2 a Roubaix con la sua bici. Dopo ore sotto la pioggia e sul pav\u00e9 arriv\u00f2 esausto in citt\u00e0 e scrisse subito una lettera invitando a rinunciare a questo \u201cprogetto diabolico\u201d. Una volta riposatosi, per\u00f2, cambi\u00f2 idea e decise di proseguire con l&#8217;organizzazione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Da quel momento la Parigi-Roubaix inizi\u00f2 a diventare una delle gare di ciclismo in Francia con pi\u00f9 partecipanti, nonostante la durezza del percorso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In uno dei paragrafi precedenti vi abbiamo detto che la gara \u00e8 stata definita \u201cInferno del Nord\u201d a causa delle difficili condizioni di corsa. In realt\u00e0, questo nome lo si deve anche ad un altro aspetto. Durante le gare successive ai due conflitti mondiali, infatti, il percorso sembrava davvero uscito da qualche film dell&#8217;orrore. Tutti gli alberi, infatti, erano inceneriti, vi erano grandi buche dovute alle esplosioni e ai bombardamenti, e anche trincee disseminate lungo il percorso.<\/span><\/p>\n<h3><strong>Alla Ricerca del Pav\u00e9 negli anni \u201890<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Solo a ridosso degli anni \u201990 del Ventesimo secolo, l&#8217;organizzazione decise di rivedere il percorso in maniera importante. Il motivo \u00e8 legato soprattutto alla mancanza di pav\u00e9 che, pian piano, veniva sostituito dal cemento per rendere pi\u00f9 agevole il passaggio di auto e furgoni. D\u2019altro canto, per\u00f2, questa gara si \u00e8 sempre contraddistinta proprio per i lunghi tratti sul pav\u00e9 e, quindi, si \u00e8 andati alla ricerca di percorsi non ancora cementificati.<\/span><\/p>\n<h2><strong>Record della Parigi-Roubaix<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Quando si parla di Parigi-Roubaix, gli occhi dei ciclisti belgi si illuminano visto che per ben 57 volte hanno vinto la manifestazione. Un numero importante e per sottolinearlo basta considerare che i francesi hanno trionfato solo in 28 occasioni. Gli italiani, invece, sono al terzo posto di questa speciale classifica con 14 vittorie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dal punto di vista individuale, invece, a guidare la classifica dei puri-vincitori abbiamo, ovviamente, due belgi. Si tratta di Roger De Vlaeminck (vincente nel 1972, 1974, 1975, 1977) e Tom Boonen (2005, 2008, 2009, 2012). Quest\u2019ultimo \u00e8 probabilmente pi\u00f9 conosciuto dai giocatori di<\/span><strong><a href=\"https:\/\/scommesse.netbet.it\/\" target=\"_blank\" rel=\"noopener\"> scommesse sportive<\/a><\/strong><span style=\"font-weight: 400;\">, in quanto vincitore anche di altri grandi classici come il Giro delle Fiandre e pi\u00f9 volte campione del mondo di ciclismo in pista.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tra gli italiani, poi, possiamo citare Francesco Moser che ha trionfato per tre anni consecutivi e precisamente dal 1978 al 1980.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019ultima edizione del 2023 \u00e8 stata vinta dall\u2019olandese Mathieu van der Poel.<\/span><\/p>\n<h2><strong>Conclusione &#8211; Ciclismo in Francia<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Eccoci giunti al termine del nostro articolo approfondito sul ciclismo in Francia e in particolare sulla Parigi-Roubaix, un evento che possiamo ormai definire classico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Abbiamo cercato di vedere la storia di questa manifestazione, i record principali, e qualche piccola curiosit\u00e0. Continuate a seguire il nostro blog aggiornato cos\u00ec da essere sempre informati sul mondo dello sport, del betting, ma anche del gambling. Nelle nostre pagine, infatti, troverete vari consigli su giochi e bonus di benvenuto e le principali strategie da applicare durante la propria esperienza di gioco.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se siete degli appassionati di ciclismo, saprete subito di cosa stiamo parlando se vi nominiamo la \u201cRegina delle Classiche\u201d. Qualora, invece, il nome non vi dicesse nulla, allora questo \u00e8 il posto giusto per voi. Nel corso di questo articolo, infatti, vedremo in maniera dettagliata tutte le caratteristiche pi\u00f9 importanti e le principali informazioni su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4772,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scommesse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciclismo In Francia: Parigi-Roubaix | NetBet Blog<\/title>\n<meta name=\"description\" content=\"Nel corso di questo articolo analizzeremo nel dettaglio uno degli eventi pi\u00f9 importanti di ciclismo in Francia, ovvero la Parigi-Roubaix.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciclismo In Francia: Parigi-Roubaix | NetBet Blog\" \/>\n<meta property=\"og:description\" content=\"Nel corso di questo articolo analizzeremo nel dettaglio uno degli eventi pi\u00f9 importanti di ciclismo in Francia, ovvero la Parigi-Roubaix.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-21T15:17:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T18:18:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1230\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\"},\"headline\":\"Ciclismo In Francia: Parigi-Roubaix\",\"datePublished\":\"2023-04-21T15:17:35+00:00\",\"dateModified\":\"2023-04-26T18:18:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\"},\"wordCount\":994,\"image\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg\",\"articleSection\":[\"Scommesse\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\",\"url\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\",\"name\":\"Ciclismo In Francia: Parigi-Roubaix | NetBet Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg\",\"datePublished\":\"2023-04-21T15:17:35+00:00\",\"dateModified\":\"2023-04-26T18:18:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\"},\"description\":\"Nel corso di questo articolo analizzeremo nel dettaglio uno degli eventi pi\u00f9 importanti di ciclismo in Francia, ovvero la Parigi-Roubaix.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage\",\"url\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg\",\"contentUrl\":\"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg\",\"width\":1230,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.netbet.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciclismo In Francia: Parigi-Roubaix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#website\",\"url\":\"https:\/\/www.netbet.it\/blog\/\",\"name\":\"NetBet Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netbet.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.netbet.it\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciclismo In Francia: Parigi-Roubaix | NetBet Blog","description":"Nel corso di questo articolo analizzeremo nel dettaglio uno degli eventi pi\u00f9 importanti di ciclismo in Francia, ovvero la Parigi-Roubaix.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/","og_locale":"it_IT","og_type":"article","og_title":"Ciclismo In Francia: Parigi-Roubaix | NetBet Blog","og_description":"Nel corso di questo articolo analizzeremo nel dettaglio uno degli eventi pi\u00f9 importanti di ciclismo in Francia, ovvero la Parigi-Roubaix.","og_url":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/","og_site_name":"NetBet Blog","article_published_time":"2023-04-21T15:17:35+00:00","article_modified_time":"2023-04-26T18:18:16+00:00","og_image":[{"width":1230,"height":630,"url":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#article","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/"},"author":{"name":"admin","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"headline":"Ciclismo In Francia: Parigi-Roubaix","datePublished":"2023-04-21T15:17:35+00:00","dateModified":"2023-04-26T18:18:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/"},"wordCount":994,"image":{"@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg","articleSection":["Scommesse"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/","url":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/","name":"Ciclismo In Francia: Parigi-Roubaix | NetBet Blog","isPartOf":{"@id":"https:\/\/www.netbet.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage"},"image":{"@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg","datePublished":"2023-04-21T15:17:35+00:00","dateModified":"2023-04-26T18:18:16+00:00","author":{"@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57"},"description":"Nel corso di questo articolo analizzeremo nel dettaglio uno degli eventi pi\u00f9 importanti di ciclismo in Francia, ovvero la Parigi-Roubaix.","breadcrumb":{"@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#primaryimage","url":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg","contentUrl":"https:\/\/www.netbet.it\/blog\/wp-content\/uploads\/2022\/04\/8.jpg","width":1230,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.netbet.it\/blog\/ciclismo-in-francia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netbet.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Ciclismo In Francia: Parigi-Roubaix"}]},{"@type":"WebSite","@id":"https:\/\/www.netbet.it\/blog\/#website","url":"https:\/\/www.netbet.it\/blog\/","name":"NetBet Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netbet.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/46b4b3318d54ed292a985534108c6b57","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.netbet.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.netbet.it\/blog\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/5503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/comments?post=5503"}],"version-history":[{"count":1,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/5503\/revisions"}],"predecessor-version":[{"id":5505,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/posts\/5503\/revisions\/5505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media\/4772"}],"wp:attachment":[{"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/media?parent=5503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/categories?post=5503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.it\/blog\/wp-json\/wp\/v2\/tags?post=5503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}